{"id":1088,"date":"2023-05-02T11:44:05","date_gmt":"2023-05-02T09:44:05","guid":{"rendered":"https:\/\/thiant.fr\/wordpress\/associations\/?p=1088"},"modified":"2023-07-17T11:20:53","modified_gmt":"2023-07-17T09:20:53","slug":"transvilles-vous-informe-sur-le-delit-dhabitude","status":"publish","type":"post","link":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/","title":{"rendered":"Transvilles vous informe sur le d\u00e9lit d&#8217;habitude"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1088\" class=\"elementor elementor-1088\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f13c008 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f13c008\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63da071\" data-id=\"63da071\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3220f9a elementor-widget elementor-widget-image\" data-id=\"3220f9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Transvilles-Logo-taille-150x43-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b00178 elementor-widget elementor-widget-text-editor\" data-id=\"8b00178\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\"><strong>KEOLIS HAINAUT VALENCIENNES<\/strong> <br \/>(filiale de KEOLIS)<\/span><\/p><p><span style=\"color: #333333;\">452, rue du Pr\u00e9sident L\u00e9cuyer<\/span><br \/><span style=\"color: #333333;\">ZI n\u00b04<\/span><br \/><span style=\"color: #333333;\">BP1<\/span><br \/><span style=\"color: #333333;\">59880 Saint Saulve<\/span><br \/><span style=\"color: #333333;\">France<\/span><\/p><p>Tel. <a href=\"tel:+33327145252\">+33 (0)3 27 14 52 52<\/a><\/p><p><a href=\"https:\/\/www.transvilles.com\" target=\"_blank\" rel=\"noopener\">www.transvilles.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-969834d elementor-widget elementor-widget-image\" data-id=\"969834d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2023\/05\/Transvilles_01-\u00a9-Samuel-Dhote.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdeea38 elementor-widget elementor-widget-image\" data-id=\"fdeea38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2023\/05\/Transvilles_02-\u00a9-Samuel-Dhote.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24ffb9c elementor-widget elementor-widget-image\" data-id=\"24ffb9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2023\/05\/Transvilles_03-\u00a9-Samuel-Dhote.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80a8bb5 elementor-widget elementor-widget-image\" data-id=\"80a8bb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2023\/05\/Transvilles_04-\u00a9-Samuel-Dhote.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bdeb0a elementor-widget elementor-widget-image\" data-id=\"3bdeb0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2023\/05\/Transvilles_05-\u00a9-Samuel-Dhote.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3e60fe elementor-widget elementor-widget-image\" data-id=\"e3e60fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2023\/05\/Transvilles_06-\u00a9-Samuel-Dhote.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-332641e elementor-widget elementor-widget-image\" data-id=\"332641e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2023\/05\/Transvilles_07-\u00a9-Samuel-Dhote.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ee907bf\" data-id=\"ee907bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4146b4e elementor-widget elementor-widget-text-editor\" data-id=\"4146b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\"><span style=\"color: #333333;\">UNE CLIENTE CONDAMN\u00c9E PAR LE TRIBUNAL <\/span><br \/><span style=\"color: #333333;\">POUR NON-PAIEMENT R\u00c9GULIER DE TITRE DE <\/span><br \/><span style=\"color: #333333;\">TRANSPORT SUR LE R\u00c9SEAU TRANSVILLES : <\/span><br \/><span style=\"color: #333333;\">LE D\u00c9LIT D\u2019HABITUDE<\/span><\/h1><p><span style=\"color: #333333;\"><strong>Le 3 mars 2023, le Tribunal correctionnel de Valenciennes a condamn\u00e9 Madame D. \u00e0 de la prison ferme et \u00e0 une sanction <\/strong><strong>financi\u00e8re dans le cadre d\u2019un d\u00e9lit d\u2019habitude, pour avoir voyag\u00e9, de <\/strong><strong>mani\u00e8re habituelle, sans titre de transport valable. L\u2019occasion, pour <\/strong><strong>Transvilles, de revenir sur la d\u00e9finition du d\u00e9lit d\u2019habitude, les <\/strong><strong>cons\u00e9quences de cette fraude caract\u00e9ris\u00e9e et plus g\u00e9n\u00e9ralement sur <\/strong><strong>l\u2019importance de l\u2019achat et la validation d\u2019un titre de transport.<\/strong><\/span><\/p><h4><span style=\"color: #000080;\"><strong>Le d\u00e9lit d\u2019habitude confirm\u00e9<\/strong> <\/span><\/h4><p><span style=\"color: #333333;\">Il a \u00e9t\u00e9 av\u00e9r\u00e9, par les pi\u00e8ces au dossier que Madame D., utilisatrice des transports en commun, a voyag\u00e9 r\u00e9guli\u00e8rement sans titre de transport entre le 21 d\u00e9cembre 2019 et le 26 mai 2020 sur le r\u00e9seau Transvilles. Malgr\u00e9 les Proc\u00e8s-Verbaux r\u00e9currents dress\u00e9s \u00e0 son encontre sur cette p\u00e9riode, aucun recouvrement des montants indiqu\u00e9s n\u2019a \u00e9t\u00e9 acquitt\u00e9.<\/span><\/p><p><span style=\"color: #333333;\">Dans le cadre de sa politique de lutte contre la fraude, Transvilles signale syst\u00e9matiquement toute r\u00e9cidive de fraude au Procureur de la R\u00e9publique pour d\u00e9lit d\u2019habitude. C\u2019est le cas de Madame D. qui a fait l\u2019objet d\u2019un d\u00e9p\u00f4t de plainte. <\/span><\/p><p><span style=\"color: #333333;\">Lors de l&#8217;audience du Tribunal Correctionnel de Valenciennes qui s\u2019est tenue le 3 mars 2023, Madame D. a \u00e9t\u00e9 reconnue coupable des faits qui lui \u00e9taient reproch\u00e9s. <\/span><br \/><span style=\"color: #333333;\">Celle-ci a \u00e9t\u00e9 <strong>condamn\u00e9e \u00e0 2 mois de prison ferme et \u00e0 verser 880 \u20ac au titre du pr\u00e9judice financier et 600 \u20ac de frais de proc\u00e9dure \u00e0 Transvilles.<\/strong><\/span><\/p><h4><span style=\"color: #000080;\">Qu\u2019est-ce que le d\u00e9lit d\u2019habitude ?<\/span><\/h4><p><span style=\"color: #333333;\">Selon l\u2019article L2242-6 du Code des transports : \u00ab Est puni de six mois d&#8217;emprisonnement et de 7 500 \u20ac d&#8217;amende le fait de voyager, de mani\u00e8re habituelle, dans tout moyen de transport public de personnes payant sans \u00eatre muni d&#8217;un titre de transport valable. L&#8217;habitude est caract\u00e9ris\u00e9e d\u00e8s lors que la personne concern\u00e9e a fait l&#8217;objet, sur une p\u00e9riode inf\u00e9rieure ou \u00e9gale \u00e0 douze mois, de plus de cinq contraventions pour avoir voyag\u00e9 sans titre de transport ou munie d&#8217;un titre de transport non valable ou non compl\u00e9t\u00e9, qui n&#8217;ont pas donn\u00e9 lieu \u00e0 une transaction en application de l&#8217;article 529-3 du code de proc\u00e9dure p\u00e9nale \u00bb. <\/span><\/p><p><span style=\"color: #333333;\">Par cette condamnation, Transvilles souhaite rappeler que valider son titre de transport est un acte obligatoire pour voyager en r\u00e8gle. La non-validation est r\u00e9pr\u00e9hensible et entraine une amende forfaitaire allant de 5\u20ac (abonnement) \u00e0 33\u20ac (ticket). L\u2019absence d\u2019un titre de transport peut entrainer, quant \u00e0 elle, une p\u00e9nalit\u00e9 financi\u00e8re de 50 \u20ac. <\/span><br \/><span style=\"color: #333333;\">Si le paiement n\u2019intervient pas sous 6 jours, l\u2019amende passe \u00e0 65\u20ac puis 88\u20ac pour ensuite \u00eatre r\u00e9gularis\u00e9e par huissier et sous 60 jours transmise au Tr\u00e9sor Public.<\/span><\/p><p><span style=\"color: #333333;\">En parall\u00e8le, le cumul de cinq contraventions dans l\u2019ann\u00e9e devient alors un <strong>d\u00e9lit d\u2019habitude<\/strong> punissable et peut \u00eatre soumis au Procureur de la r\u00e9publique.<\/span><\/p><h4><span style=\"color: #000080;\">La validation, un acte obligatoire <\/span><\/h4><p><span style=\"color: #333333;\">Au-del\u00e0 du caract\u00e8re r\u00e9glementaire de cet acte, les validations permettent de mesurer la fr\u00e9quentation sur les lignes, en fonction des arr\u00eats et des tranches horaires. Elles servent \u00e0 dessiner une cartographie pr\u00e9cise de l\u2019affluence sur le r\u00e9seau pour pouvoir adapter les moyens humains et techniques aux besoins des clients. <\/span><\/p><p><span style=\"color: #333333;\">Le contrevenant a la possibilit\u00e9 de r\u00e9gler directement aupr\u00e8s de l\u2019\u00e9quipe de contr\u00f4le ou sous 24h dans l\u2019une de nos deux agences commerciales de Valenciennes et Denain.<\/span><\/p><p><span style=\"color: #333333;\"><small>Le nom de la contrevenante a volontairement \u00e9t\u00e9 modifi\u00e9 dans un souci d\u2019anonymat.<\/small><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>KEOLIS HAINAUT VALENCIENNES (filiale de KEOLIS) 452, rue du Pr\u00e9sident L\u00e9cuyer ZI n\u00b04 BP1 59880 Saint Saulve France Tel. +33 (0)3 27 14 52 52 www.transvilles.com UNE CLIENTE CONDAMN\u00c9E PAR LE TRIBUNAL POUR NON-PAIEMENT R\u00c9GULIER DE TITRE DE TRANSPORT SUR LE R\u00c9SEAU TRANSVILLES : LE D\u00c9LIT D\u2019HABITUDE Le 3 mars 2023, le Tribunal correctionnel de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[311,584,585,586,587,156,588,589,590],"class_list":["post-1088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","tag-delit","tag-delit-dhabitude","tag-habitude","tag-prison","tag-titre-de-transport","tag-transvilles","tag-validation","tag-valider","tag-voyage","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transvilles vous informe sur le d\u00e9lit d&#039;habitude - Les associations de la ville de Thiant<\/title>\n<meta name=\"description\" content=\"Une personne a \u00e9t\u00e9 condamn\u00e9e \u00e0 de la prison ferme et \u00e0 une sanction financi\u00e8re dans le cadre d&#039;un d\u00e9lit d&#039;habitude. Explications.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transvilles vous informe sur le d\u00e9lit d&#039;habitude - Les associations de la ville de Thiant\" \/>\n<meta property=\"og:description\" content=\"Une personne a \u00e9t\u00e9 condamn\u00e9e \u00e0 de la prison ferme et \u00e0 une sanction financi\u00e8re dans le cadre d&#039;un d\u00e9lit d&#039;habitude. Explications.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/\" \/>\n<meta property=\"og:site_name\" content=\"Les associations de la ville de Thiant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/commune.thiant.1\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-02T09:44:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-17T09:20:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2023\/05\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Service communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/\"},\"author\":{\"name\":\"Service communication\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\"},\"headline\":\"Transvilles vous informe sur le d\u00e9lit d&#8217;habitude\",\"datePublished\":\"2023-05-02T09:44:05+00:00\",\"dateModified\":\"2023-07-17T09:20:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/\"},\"wordCount\":657,\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png\",\"keywords\":[\"d\u00e9lit\",\"d\u00e9lit d&#039;habitude\",\"habitude\",\"prison\",\"titre de transport\",\"transvilles\",\"validation\",\"valider\",\"voyage\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/\",\"name\":\"Transvilles vous informe sur le d\u00e9lit d'habitude - Les associations de la ville de Thiant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png\",\"datePublished\":\"2023-05-02T09:44:05+00:00\",\"dateModified\":\"2023-07-17T09:20:53+00:00\",\"description\":\"Une personne a \u00e9t\u00e9 condamn\u00e9e \u00e0 de la prison ferme et \u00e0 une sanction financi\u00e8re dans le cadre d'un d\u00e9lit d'habitude. Explications.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/05\\\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png\",\"width\":730,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/transvilles-vous-informe-sur-le-delit-dhabitude\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transvilles vous informe sur le d\u00e9lit d&#8217;habitude\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#website\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/\",\"name\":\"Les associations de la ville de Thiant\",\"description\":\"Retrouvez toutes les associations de la ville\",\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#organization\",\"name\":\"Les associations de la ville de Thiant\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/cropped-logo-asso-75.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/cropped-logo-asso-75.png\",\"width\":75,\"height\":75,\"caption\":\"Les associations de la ville de Thiant\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/commune.thiant.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\",\"name\":\"Service communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/litespeed\\\/avatar\\\/3\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787764658\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/litespeed\\\/avatar\\\/3\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787764658\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/wp-content\\\/litespeed\\\/avatar\\\/3\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787764658\",\"caption\":\"Service communication\"},\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/associations\\\/author\\\/adminwpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transvilles vous informe sur le d\u00e9lit d'habitude - Les associations de la ville de Thiant","description":"Une personne a \u00e9t\u00e9 condamn\u00e9e \u00e0 de la prison ferme et \u00e0 une sanction financi\u00e8re dans le cadre d'un d\u00e9lit d'habitude. Explications.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/","og_locale":"fr_FR","og_type":"article","og_title":"Transvilles vous informe sur le d\u00e9lit d'habitude - Les associations de la ville de Thiant","og_description":"Une personne a \u00e9t\u00e9 condamn\u00e9e \u00e0 de la prison ferme et \u00e0 une sanction financi\u00e8re dans le cadre d'un d\u00e9lit d'habitude. Explications.","og_url":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/","og_site_name":"Les associations de la ville de Thiant","article_publisher":"https:\/\/www.facebook.com\/commune.thiant.1","article_published_time":"2023-05-02T09:44:05+00:00","article_modified_time":"2023-07-17T09:20:53+00:00","og_image":[{"width":730,"height":487,"url":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2023\/05\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png","type":"image\/png"}],"author":"Service communication","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service communication","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/#article","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/"},"author":{"name":"Service communication","@id":"https:\/\/thiant.fr\/wordpress\/associations\/#\/schema\/person\/f41122130d18c0720657431d990451c6"},"headline":"Transvilles vous informe sur le d\u00e9lit d&#8217;habitude","datePublished":"2023-05-02T09:44:05+00:00","dateModified":"2023-07-17T09:20:53+00:00","mainEntityOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/"},"wordCount":657,"publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/#organization"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2023\/05\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png","keywords":["d\u00e9lit","d\u00e9lit d&#039;habitude","habitude","prison","titre de transport","transvilles","validation","valider","voyage"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/","url":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/","name":"Transvilles vous informe sur le d\u00e9lit d'habitude - Les associations de la ville de Thiant","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/#primaryimage"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2023\/05\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png","datePublished":"2023-05-02T09:44:05+00:00","dateModified":"2023-07-17T09:20:53+00:00","description":"Une personne a \u00e9t\u00e9 condamn\u00e9e \u00e0 de la prison ferme et \u00e0 une sanction financi\u00e8re dans le cadre d'un d\u00e9lit d'habitude. Explications.","breadcrumb":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/#primaryimage","url":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2023\/05\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2023\/05\/Visuel-Transvilles-\u00a9-Samuel-Dhote.png","width":730,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/thiant.fr\/wordpress\/associations\/transvilles-vous-informe-sur-le-delit-dhabitude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thiant.fr\/wordpress\/associations\/"},{"@type":"ListItem","position":2,"name":"Transvilles vous informe sur le d\u00e9lit d&#8217;habitude"}]},{"@type":"WebSite","@id":"https:\/\/thiant.fr\/wordpress\/associations\/#website","url":"https:\/\/thiant.fr\/wordpress\/associations\/","name":"Les associations de la ville de Thiant","description":"Retrouvez toutes les associations de la ville","publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thiant.fr\/wordpress\/associations\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thiant.fr\/wordpress\/associations\/#organization","name":"Les associations de la ville de Thiant","url":"https:\/\/thiant.fr\/wordpress\/associations\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/associations\/#\/schema\/logo\/image\/","url":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2024\/11\/cropped-logo-asso-75.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/uploads\/sites\/3\/2024\/11\/cropped-logo-asso-75.png","width":75,"height":75,"caption":"Les associations de la ville de Thiant"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/associations\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/commune.thiant.1"]},{"@type":"Person","@id":"https:\/\/thiant.fr\/wordpress\/associations\/#\/schema\/person\/f41122130d18c0720657431d990451c6","name":"Service communication","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/litespeed\/avatar\/3\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787764658","url":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/litespeed\/avatar\/3\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787764658","contentUrl":"https:\/\/thiant.fr\/wordpress\/associations\/wp-content\/litespeed\/avatar\/3\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787764658","caption":"Service communication"},"url":"https:\/\/thiant.fr\/wordpress\/associations\/author\/adminwpress\/"}]}},"_links":{"self":[{"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/posts\/1088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/comments?post=1088"}],"version-history":[{"count":6,"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/posts\/1088\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/posts\/1088\/revisions\/1187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/media\/1089"}],"wp:attachment":[{"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/media?parent=1088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/categories?post=1088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/associations\/wp-json\/wp\/v2\/tags?post=1088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}