{"id":192,"date":"2019-11-08T15:53:30","date_gmt":"2019-11-08T14:53:30","guid":{"rendered":"https:\/\/thiant.fr\/wordpress\/\/wordpress\/jeunesse\/?p=192"},"modified":"2024-07-11T17:19:09","modified_gmt":"2024-07-11T15:19:09","slug":"ateliers-numeriques-saison-3","status":"publish","type":"post","link":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/","title":{"rendered":"Ateliers num\u00e9riques saison 3"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"192\" class=\"elementor elementor-192\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94e1c6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94e1c6f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1734cf6\" data-id=\"1734cf6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02e4df6 elementor-widget elementor-widget-image\" data-id=\"02e4df6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"412\" height=\"287\" src=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg\" class=\"attachment-large size-large wp-image-194\" alt=\"\" srcset=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg 412w, https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3-300x209.jpg 300w\" sizes=\"(max-width: 412px) 100vw, 412px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05c5c2e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05c5c2e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89a9c6c\" data-id=\"89a9c6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f667d71 elementor-widget elementor-widget-text-editor\" data-id=\"f667d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLa saison 3 des ateliers num\u00e9riques gratuits propos\u00e9s par la CAPH est lanc\u00e9e ! Trois dates \u00e0 retenir :\n<ul>\n \t<li>20 novembre (14h-16h) : Faire face au harc\u00e8lement sur les r\u00e9seaux sociaux (\u00e0 partir de 11 ans)<\/li>\n \t<li>14 d\u00e9cembre (10h-12h) : L&#8217;impression 3D pour les enfants (\u00e0 partir de 6 ans)<\/li>\n \t<li>21 d\u00e9cembre (10h-12h) : D\u00e9celer les arnaques et agir contre les virus informatiques (\u00e0 partir de 12 ans)<\/li>\n<\/ul>\nAnim\u00e9s par des intervenants professionnels de qualit\u00e9, ces ateliers sont l&#8217;occasion d&#8217;\u00e9changes et de partages de connaissances. Toutes les questions que vous pouvez vous poser sur ces sujets y trouveront leur r\u00e9ponse. alors n&#8217;h\u00e9sitez pas \u00e0 vous inscrire ! Tous ces ateliers se d\u00e9roulent \u00e0 l&#8217;Espace Jeune, salle Boon, 2 rue du Docteur Roux.\n\nPour vous inscrire :<\/br>\n<h4><a href=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/events\/atelier-numerique-gratuit-de-la-caph-2\/\">Faire face au harc\u00e8lement sur les r\u00e9seaux sociaux<\/a><\/h4><\/br>\n<h4><a href=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/events\/atelier-numerique-gratuit-de-la-caph\/\">L&#8217;impression 3D<\/a><\/h4><\/br>\n<h4><a href=\"https:\/\/thiant.fr\/wordpress\/evenements\/atelier-numerique-gratuit-propose-par-la-caph\/\">D\u00e9celer les arnaques et agir contre les virus informatiques<\/a><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La saison 3 des ateliers num\u00e9riques gratuits propos\u00e9s par la CAPH est lanc\u00e9e ! Trois dates \u00e0 retenir : 20 novembre (14h-16h) : Faire face au harc\u00e8lement sur les r\u00e9seaux sociaux (\u00e0 partir de 11 ans) 14 d\u00e9cembre (10h-12h) : L&#8217;impression 3D pour les enfants (\u00e0 partir de 6 ans) 21 d\u00e9cembre (10h-12h) : D\u00e9celer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-192","post","type-post","status-publish","format-standard","hentry","category-non-classe","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ateliers num\u00e9riques saison 3 - Espace jeunesse du site officiel de la Ville de Thiant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ateliers num\u00e9riques saison 3 - Espace jeunesse du site officiel de la Ville de Thiant\" \/>\n<meta property=\"og:description\" content=\"La saison 3 des ateliers num\u00e9riques gratuits propos\u00e9s par la CAPH est lanc\u00e9e ! Trois dates \u00e0 retenir : 20 novembre (14h-16h) : Faire face au harc\u00e8lement sur les r\u00e9seaux sociaux (\u00e0 partir de 11 ans) 14 d\u00e9cembre (10h-12h) : L&#8217;impression 3D pour les enfants (\u00e0 partir de 6 ans) 21 d\u00e9cembre (10h-12h) : D\u00e9celer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Espace jeunesse du site officiel de la Ville de Thiant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/commune.thiant.1\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-08T14:53:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T15:19:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thiant.fr\/wordpress\/\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg\" \/>\n<meta name=\"author\" content=\"Service communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/\"},\"author\":{\"name\":\"Service communication\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\"},\"headline\":\"Ateliers num\u00e9riques saison 3\",\"datePublished\":\"2019-11-08T14:53:30+00:00\",\"dateModified\":\"2024-07-11T15:19:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/\"},\"wordCount\":152,\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/visuel_At-Num_S3.jpg\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/\",\"name\":\"Ateliers num\u00e9riques saison 3 - Espace jeunesse du site officiel de la Ville de Thiant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/visuel_At-Num_S3.jpg\",\"datePublished\":\"2019-11-08T14:53:30+00:00\",\"dateModified\":\"2024-07-11T15:19:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/visuel_At-Num_S3.jpg\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/visuel_At-Num_S3.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2019\\\/11\\\/08\\\/ateliers-numeriques-saison-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ateliers num\u00e9riques saison 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#website\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\",\"name\":\"Espace jeunesse du site officiel de la Ville de Thiant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\",\"name\":\"Espace jeunesse du site officiel de la Ville de Thiant\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Logo_jeunesse_02-1.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Logo_jeunesse_02-1.png\",\"width\":384,\"height\":203,\"caption\":\"Espace jeunesse du site officiel de la Ville de Thiant\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/commune.thiant.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\",\"name\":\"Service communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"caption\":\"Service communication\"},\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/author\\\/adminwpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ateliers num\u00e9riques saison 3 - Espace jeunesse du site officiel de la Ville de Thiant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/","og_locale":"fr_FR","og_type":"article","og_title":"Ateliers num\u00e9riques saison 3 - Espace jeunesse du site officiel de la Ville de Thiant","og_description":"La saison 3 des ateliers num\u00e9riques gratuits propos\u00e9s par la CAPH est lanc\u00e9e ! Trois dates \u00e0 retenir : 20 novembre (14h-16h) : Faire face au harc\u00e8lement sur les r\u00e9seaux sociaux (\u00e0 partir de 11 ans) 14 d\u00e9cembre (10h-12h) : L&#8217;impression 3D pour les enfants (\u00e0 partir de 6 ans) 21 d\u00e9cembre (10h-12h) : D\u00e9celer [&hellip;]","og_url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/","og_site_name":"Espace jeunesse du site officiel de la Ville de Thiant","article_publisher":"https:\/\/www.facebook.com\/commune.thiant.1","article_published_time":"2019-11-08T14:53:30+00:00","article_modified_time":"2024-07-11T15:19:09+00:00","og_image":[{"url":"https:\/\/thiant.fr\/wordpress\/\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg","type":"","width":"","height":""}],"author":"Service communication","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service communication","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/#article","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/"},"author":{"name":"Service communication","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/person\/f41122130d18c0720657431d990451c6"},"headline":"Ateliers num\u00e9riques saison 3","datePublished":"2019-11-08T14:53:30+00:00","dateModified":"2024-07-11T15:19:09+00:00","mainEntityOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/"},"wordCount":152,"publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg","inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/","name":"Ateliers num\u00e9riques saison 3 - Espace jeunesse du site officiel de la Ville de Thiant","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/#primaryimage"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg","datePublished":"2019-11-08T14:53:30+00:00","dateModified":"2024-07-11T15:19:09+00:00","breadcrumb":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/#primaryimage","url":"https:\/\/thiant.fr\/wordpress\/\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg","contentUrl":"https:\/\/thiant.fr\/wordpress\/\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/11\/visuel_At-Num_S3.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2019\/11\/08\/ateliers-numeriques-saison-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thiant.fr\/wordpress\/jeunesse\/"},{"@type":"ListItem","position":2,"name":"Ateliers num\u00e9riques saison 3"}]},{"@type":"WebSite","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#website","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/","name":"Espace jeunesse du site officiel de la Ville de Thiant","description":"","publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thiant.fr\/wordpress\/jeunesse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization","name":"Espace jeunesse du site officiel de la Ville de Thiant","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/logo\/image\/","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/10\/Logo_jeunesse_02-1.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/10\/Logo_jeunesse_02-1.png","width":384,"height":203,"caption":"Espace jeunesse du site officiel de la Ville de Thiant"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/commune.thiant.1"]},{"@type":"Person","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/person\/f41122130d18c0720657431d990451c6","name":"Service communication","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","contentUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","caption":"Service communication"},"url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/author\/adminwpress\/"}]}},"_links":{"self":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/comments?post=192"}],"version-history":[{"count":3,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/192\/revisions"}],"predecessor-version":[{"id":196,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/192\/revisions\/196"}],"wp:attachment":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/media?parent=192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/categories?post=192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/tags?post=192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}