{"id":324,"date":"2020-03-06T15:32:50","date_gmt":"2020-03-06T14:32:50","guid":{"rendered":"https:\/\/thiant.fr\/wordpress\/jeunesse\/?p=324"},"modified":"2020-03-06T16:06:48","modified_gmt":"2020-03-06T15:06:48","slug":"accueils-de-loisirs-2020","status":"publish","type":"post","link":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/","title":{"rendered":"Accueils de loisirs 2020"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"324\" class=\"elementor elementor-324\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0ca023 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0ca023\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0cbfdf0\" data-id=\"0cbfdf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6c6d86 elementor-widget elementor-widget-text-editor\" data-id=\"f6c6d86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><span style=\"color: #3366ff;\">Du <span style=\"color: #ff0000;\">6<\/span> au <span style=\"color: #ff0000;\">30<\/span> juillet 2020<\/span><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8786dd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8786dd8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba79992\" data-id=\"ba79992\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff5b0ff elementor-widget elementor-widget-text-editor\" data-id=\"ff5b0ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5 style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>INSCRIPTIONS<\/strong> (Salle du temps de vivre)<\/span><\/h5><h6 style=\"text-align: center;\"><span style=\"color: #ff0000;\">Samedi 4 avril de 9h \u00e0 13h et <\/span><span style=\"color: #ff0000;\">mercredi 8 avril de 9h \u00e0 13h<\/span><\/h6><p><span style=\"color: #333333;\">Les dossiers sont \u00e0 retirer en mairie <strong>\u00e0 partir du 16 mars<\/strong>.<\/span><br \/><span style=\"color: #333333;\">Les inscriptions se feront uniquement \u00e0 ces dates. En dehors ou au-del\u00e0 de ces dates, les inscriptions sont susceptibles de ne pas \u00eatre prises en compte (notamment en fonction des places disponibles).<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71bae81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71bae81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0ec964\" data-id=\"e0ec964\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22e67e6 elementor-widget elementor-widget-text-editor\" data-id=\"22e67e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span style=\"color: #333333;\">Petite enfance<\/span><\/h6><p><span style=\"color: #333333;\">Les enfants inscrits pendant l\u2019ann\u00e9e scolaire 2019\/2020 \u00e0 l\u2019\u00e9cole maternelle, de la petite section \u00e0 la grande section.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-877425d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"877425d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7981eb1\" data-id=\"7981eb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa15bf9 elementor-widget elementor-widget-text-editor\" data-id=\"fa15bf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span style=\"color: #333333;\">\u00c9l\u00e9mentaire<\/span><\/h6><p><span style=\"color: #333333;\">Les enfants inscrits pendant l\u2019ann\u00e9e scolaire 2019\/2020 \u00e0 l\u2019\u00e9cole \u00e9l\u00e9mentaire et au coll\u00e8ge jusqu\u2019\u00e0 14 ans.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b03f8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b03f8d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d87fc8d\" data-id=\"d87fc8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-243fd74 elementor-widget elementor-widget-text-editor\" data-id=\"243fd74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span style=\"color: #333333;\">Adolescents<\/span><\/h6><p><span style=\"color: #333333;\">Les jeunes \u00e2g\u00e9s de 15 \u00e0 17 ans.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6212753 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6212753\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c7ea31\" data-id=\"5c7ea31\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1987d6c elementor-widget elementor-widget-image\" data-id=\"1987d6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"254\" src=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/footer.png\" class=\"attachment-full size-full wp-image-326\" alt=\"\" srcset=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/footer.png 750w, https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/footer-300x102.png 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Du 6 au 30 juillet 2020 INSCRIPTIONS (Salle du temps de vivre) Samedi 4 avril de 9h \u00e0 13h et mercredi 8 avril de 9h \u00e0 13h Les dossiers sont \u00e0 retirer en mairie \u00e0 partir du 16 mars. Les inscriptions se feront uniquement \u00e0 ces dates. En dehors ou au-del\u00e0 de ces dates, les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":325,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[41,56],"tags":[111,42,116,112,115,113,110,114,39],"class_list":["post-324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alsh","category-jeunesse","tag-accueils-de-loisirs","tag-alsh","tag-asolescents","tag-centre-aere","tag-elementaires","tag-inscriptions","tag-juillet","tag-petite-enfance","tag-thiant","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accueils de loisirs 2020 - Espace jeunesse du site officiel de la Ville de Thiant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accueils de loisirs 2020 - Espace jeunesse du site officiel de la Ville de Thiant\" \/>\n<meta property=\"og:description\" content=\"Du 6 au 30 juillet 2020 INSCRIPTIONS (Salle du temps de vivre) Samedi 4 avril de 9h \u00e0 13h et mercredi 8 avril de 9h \u00e0 13h Les dossiers sont \u00e0 retirer en mairie \u00e0 partir du 16 mars. Les inscriptions se feront uniquement \u00e0 ces dates. En dehors ou au-del\u00e0 de ces dates, les [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Espace jeunesse du site officiel de la Ville de Thiant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/commune.thiant.1\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-06T14:32:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-06T15:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/accroche.png\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Service communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/\"},\"author\":{\"name\":\"Service communication\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\"},\"headline\":\"Accueils de loisirs 2020\",\"datePublished\":\"2020-03-06T14:32:50+00:00\",\"dateModified\":\"2020-03-06T15:06:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/\"},\"wordCount\":110,\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/accroche.png\",\"keywords\":[\"accueils de loisirs\",\"ALSH\",\"asolescents\",\"centre a\u00e9r\u00e9\",\"\u00e9l\u00e9mentaires\",\"inscriptions\",\"juillet\",\"petite enfance\",\"thiant\"],\"articleSection\":[\"ALSH\",\"Jeunesse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/\",\"name\":\"Accueils de loisirs 2020 - Espace jeunesse du site officiel de la Ville de Thiant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/accroche.png\",\"datePublished\":\"2020-03-06T14:32:50+00:00\",\"dateModified\":\"2020-03-06T15:06:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/accroche.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/03\\\/accroche.png\",\"width\":750,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/06\\\/accueils-de-loisirs-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueils de loisirs 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#website\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\",\"name\":\"Espace jeunesse du site officiel de la Ville de Thiant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\",\"name\":\"Espace jeunesse du site officiel de la Ville de Thiant\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Logo_jeunesse_02-1.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Logo_jeunesse_02-1.png\",\"width\":384,\"height\":203,\"caption\":\"Espace jeunesse du site officiel de la Ville de Thiant\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/commune.thiant.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\",\"name\":\"Service communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"caption\":\"Service communication\"},\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/author\\\/adminwpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueils de loisirs 2020 - Espace jeunesse du site officiel de la Ville de Thiant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/","og_locale":"fr_FR","og_type":"article","og_title":"Accueils de loisirs 2020 - Espace jeunesse du site officiel de la Ville de Thiant","og_description":"Du 6 au 30 juillet 2020 INSCRIPTIONS (Salle du temps de vivre) Samedi 4 avril de 9h \u00e0 13h et mercredi 8 avril de 9h \u00e0 13h Les dossiers sont \u00e0 retirer en mairie \u00e0 partir du 16 mars. Les inscriptions se feront uniquement \u00e0 ces dates. En dehors ou au-del\u00e0 de ces dates, les [&hellip;]","og_url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/","og_site_name":"Espace jeunesse du site officiel de la Ville de Thiant","article_publisher":"https:\/\/www.facebook.com\/commune.thiant.1","article_published_time":"2020-03-06T14:32:50+00:00","article_modified_time":"2020-03-06T15:06:48+00:00","og_image":[{"width":750,"height":350,"url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/accroche.png","type":"image\/png"}],"author":"Service communication","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service communication","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/#article","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/"},"author":{"name":"Service communication","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/person\/f41122130d18c0720657431d990451c6"},"headline":"Accueils de loisirs 2020","datePublished":"2020-03-06T14:32:50+00:00","dateModified":"2020-03-06T15:06:48+00:00","mainEntityOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/"},"wordCount":110,"publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/accroche.png","keywords":["accueils de loisirs","ALSH","asolescents","centre a\u00e9r\u00e9","\u00e9l\u00e9mentaires","inscriptions","juillet","petite enfance","thiant"],"articleSection":["ALSH","Jeunesse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/","name":"Accueils de loisirs 2020 - Espace jeunesse du site officiel de la Ville de Thiant","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/#primaryimage"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/accroche.png","datePublished":"2020-03-06T14:32:50+00:00","dateModified":"2020-03-06T15:06:48+00:00","breadcrumb":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/#primaryimage","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/accroche.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2020\/03\/accroche.png","width":750,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/06\/accueils-de-loisirs-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thiant.fr\/wordpress\/jeunesse\/"},{"@type":"ListItem","position":2,"name":"Accueils de loisirs 2020"}]},{"@type":"WebSite","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#website","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/","name":"Espace jeunesse du site officiel de la Ville de Thiant","description":"","publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thiant.fr\/wordpress\/jeunesse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization","name":"Espace jeunesse du site officiel de la Ville de Thiant","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/logo\/image\/","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/10\/Logo_jeunesse_02-1.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/10\/Logo_jeunesse_02-1.png","width":384,"height":203,"caption":"Espace jeunesse du site officiel de la Ville de Thiant"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/commune.thiant.1"]},{"@type":"Person","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/person\/f41122130d18c0720657431d990451c6","name":"Service communication","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","contentUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","caption":"Service communication"},"url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/author\/adminwpress\/"}]}},"_links":{"self":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/comments?post=324"}],"version-history":[{"count":8,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/324\/revisions"}],"predecessor-version":[{"id":335,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/324\/revisions\/335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/media\/325"}],"wp:attachment":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/media?parent=324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/categories?post=324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/tags?post=324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}