{"id":356,"date":"2020-03-16T17:50:57","date_gmt":"2020-03-16T16:50:57","guid":{"rendered":"https:\/\/thiant.fr\/wordpress\/jeunesse\/?p=356"},"modified":"2020-03-16T18:19:59","modified_gmt":"2020-03-16T17:19:59","slug":"alsh-de-juillet","status":"publish","type":"post","link":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/","title":{"rendered":"ALSH de Juillet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"356\" class=\"elementor elementor-356\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4605252 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4605252\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6077d4\" data-id=\"b6077d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05f2653 elementor-widget elementor-widget-text-editor\" data-id=\"05f2653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><span style=\"color: #993300;\">Le dossier d&#8217;inscription et la plaquette d&#8217;information sont disponibles sur ce site internet dans la colonne de droite sous <br \/>&#8220;Les documents essentiels&#8221;.<\/span><\/h4><h5 style=\"text-align: center;\"><span style=\"color: #ff0000;\">!!! Les inscriptions des 4 et 8 avril sont report\u00e9es \u00e0 une date ult\u00e9rieure !!!<\/span><\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8df8012 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8df8012\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ede4b25\" data-id=\"ede4b25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f364a0e elementor-widget elementor-widget-text-editor\" data-id=\"f364a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333;\">Le dossier d&#8217;inscription doit \u00eatre envoy\u00e9 par courrier \u00e9lectronique \u00e0 l&#8217;adresse <span style=\"color: #ff6600;\">alsh@thiant.fr <span style=\"color: #333333;\">accompagn\u00e9 des documents demand\u00e9s (scann\u00e9s ou pris en photo). Si possible modifier le nom des documents envoy\u00e9s en indiquant le nom et pr\u00e9nom de l&#8217;enfant. Merci de votre compr\u00e9hension.<\/span><\/span><br \/><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le dossier d&#8217;inscription et la plaquette d&#8217;information sont disponibles sur ce site internet dans la colonne de droite sous &#8220;Les documents essentiels&#8221;. !!! Les inscriptions des 4 et 8 avril sont report\u00e9es \u00e0 une date ult\u00e9rieure !!! Le dossier d&#8217;inscription doit \u00eatre envoy\u00e9 par courrier \u00e9lectronique \u00e0 l&#8217;adresse alsh@thiant.fr accompagn\u00e9 des documents demand\u00e9s (scann\u00e9s ou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[41],"tags":[42,137,110,139],"class_list":["post-356","post","type-post","status-publish","format-standard","hentry","category-alsh","tag-alsh","tag-dossier-inscription","tag-juillet","tag-renseignements","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALSH de Juillet - Espace jeunesse du site officiel de la Ville de Thiant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALSH de Juillet - Espace jeunesse du site officiel de la Ville de Thiant\" \/>\n<meta property=\"og:description\" content=\"Le dossier d&#8217;inscription et la plaquette d&#8217;information sont disponibles sur ce site internet dans la colonne de droite sous &#8220;Les documents essentiels&#8221;. !!! Les inscriptions des 4 et 8 avril sont report\u00e9es \u00e0 une date ult\u00e9rieure !!! Le dossier d&#8217;inscription doit \u00eatre envoy\u00e9 par courrier \u00e9lectronique \u00e0 l&#8217;adresse alsh@thiant.fr accompagn\u00e9 des documents demand\u00e9s (scann\u00e9s ou [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/\" \/>\n<meta property=\"og:site_name\" content=\"Espace jeunesse du site officiel de la Ville de Thiant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/commune.thiant.1\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-16T16:50:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-16T17:19:59+00:00\" \/>\n<meta name=\"author\" content=\"Service communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service communication\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/\"},\"author\":{\"name\":\"Service communication\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\"},\"headline\":\"ALSH de Juillet\",\"datePublished\":\"2020-03-16T16:50:57+00:00\",\"dateModified\":\"2020-03-16T17:19:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/\"},\"wordCount\":89,\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\"},\"keywords\":[\"ALSH\",\"dossier inscription\",\"juillet\",\"renseignements\"],\"articleSection\":[\"ALSH\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/\",\"name\":\"ALSH de Juillet - Espace jeunesse du site officiel de la Ville de Thiant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#website\"},\"datePublished\":\"2020-03-16T16:50:57+00:00\",\"dateModified\":\"2020-03-16T17:19:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/2020\\\/03\\\/16\\\/alsh-de-juillet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALSH de Juillet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#website\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\",\"name\":\"Espace jeunesse du site officiel de la Ville de Thiant\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#organization\",\"name\":\"Espace jeunesse du site officiel de la Ville de Thiant\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Logo_jeunesse_02-1.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/Logo_jeunesse_02-1.png\",\"width\":384,\"height\":203,\"caption\":\"Espace jeunesse du site officiel de la Ville de Thiant\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/commune.thiant.1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\",\"name\":\"Service communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/wp-content\\\/litespeed\\\/avatar\\\/2\\\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894\",\"caption\":\"Service communication\"},\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/jeunesse\\\/author\\\/adminwpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALSH de Juillet - Espace jeunesse du site officiel de la Ville de Thiant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/","og_locale":"fr_FR","og_type":"article","og_title":"ALSH de Juillet - Espace jeunesse du site officiel de la Ville de Thiant","og_description":"Le dossier d&#8217;inscription et la plaquette d&#8217;information sont disponibles sur ce site internet dans la colonne de droite sous &#8220;Les documents essentiels&#8221;. !!! Les inscriptions des 4 et 8 avril sont report\u00e9es \u00e0 une date ult\u00e9rieure !!! Le dossier d&#8217;inscription doit \u00eatre envoy\u00e9 par courrier \u00e9lectronique \u00e0 l&#8217;adresse alsh@thiant.fr accompagn\u00e9 des documents demand\u00e9s (scann\u00e9s ou [&hellip;]","og_url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/","og_site_name":"Espace jeunesse du site officiel de la Ville de Thiant","article_publisher":"https:\/\/www.facebook.com\/commune.thiant.1","article_published_time":"2020-03-16T16:50:57+00:00","article_modified_time":"2020-03-16T17:19:59+00:00","author":"Service communication","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service communication"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/#article","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/"},"author":{"name":"Service communication","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/person\/f41122130d18c0720657431d990451c6"},"headline":"ALSH de Juillet","datePublished":"2020-03-16T16:50:57+00:00","dateModified":"2020-03-16T17:19:59+00:00","mainEntityOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/"},"wordCount":89,"publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization"},"keywords":["ALSH","dossier inscription","juillet","renseignements"],"articleSection":["ALSH"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/","name":"ALSH de Juillet - Espace jeunesse du site officiel de la Ville de Thiant","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#website"},"datePublished":"2020-03-16T16:50:57+00:00","dateModified":"2020-03-16T17:19:59+00:00","breadcrumb":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/2020\/03\/16\/alsh-de-juillet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thiant.fr\/wordpress\/jeunesse\/"},{"@type":"ListItem","position":2,"name":"ALSH de Juillet"}]},{"@type":"WebSite","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#website","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/","name":"Espace jeunesse du site officiel de la Ville de Thiant","description":"","publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thiant.fr\/wordpress\/jeunesse\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#organization","name":"Espace jeunesse du site officiel de la Ville de Thiant","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/logo\/image\/","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/10\/Logo_jeunesse_02-1.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/uploads\/sites\/2\/2019\/10\/Logo_jeunesse_02-1.png","width":384,"height":203,"caption":"Espace jeunesse du site officiel de la Ville de Thiant"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/commune.thiant.1"]},{"@type":"Person","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/#\/schema\/person\/f41122130d18c0720657431d990451c6","name":"Service communication","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","contentUrl":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-content\/litespeed\/avatar\/2\/eeb9098e5269f97d4e67fcd6f533ccb1.jpg?ver=1787753894","caption":"Service communication"},"url":"https:\/\/thiant.fr\/wordpress\/jeunesse\/author\/adminwpress\/"}]}},"_links":{"self":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/comments?post=356"}],"version-history":[{"count":8,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/356\/revisions"}],"predecessor-version":[{"id":368,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/posts\/356\/revisions\/368"}],"wp:attachment":[{"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/media?parent=356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/categories?post=356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/jeunesse\/wp-json\/wp\/v2\/tags?post=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}