{"id":1630,"date":"2020-10-05T14:22:03","date_gmt":"2020-10-05T12:22:03","guid":{"rendered":"https:\/\/thiant.fr\/wordpress\/?p=1630"},"modified":"2020-10-14T15:52:13","modified_gmt":"2020-10-14T13:52:13","slug":"campagne-de-validation","status":"publish","type":"post","link":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/","title":{"rendered":"Campagne de validation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1630\" class=\"elementor elementor-1630\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae85593 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae85593\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-df0afca\" data-id=\"df0afca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49b18f0 elementor-widget elementor-widget-text-editor\" data-id=\"49b18f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 style=\"text-align: center;\"><span style=\"color: #008000;\">TRANSVILLES RAPPELLE A SES CLIENTS<br \/>AVEC HUMOUR L\u2019IMPORTANCE DE VALIDER<\/span><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db063b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db063b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e8beb0d\" data-id=\"e8beb0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20a8f81 elementor-widget__width-initial elementor-widget elementor-widget-image-gallery\" data-id=\"20a8f81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-1630 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-01.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"355\" height=\"500\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-01.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-01.jpg 355w, https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-01-213x300.jpg 213w\" sizes=\"(max-width: 355px) 100vw, 355px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-02.jpg'><img decoding=\"async\" width=\"354\" height=\"499\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-02.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-02.jpg 354w, https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-02-213x300.jpg 213w\" sizes=\"(max-width: 354px) 100vw, 354px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-03.jpg'><img decoding=\"async\" width=\"354\" height=\"499\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-03.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-03.jpg 354w, https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-03-213x300.jpg 213w\" sizes=\"(max-width: 354px) 100vw, 354px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-04.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"500\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-04.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-04.jpg 355w, https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-04-213x300.jpg 213w\" sizes=\"(max-width: 355px) 100vw, 355px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-05.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"500\" src=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-05.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-05.jpg 355w, https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/10\/Affiche_validation-05-213x300.jpg 213w\" sizes=\"(max-width: 355px) 100vw, 355px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-d41e00e\" data-id=\"d41e00e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2826f3a elementor-widget elementor-widget-text-editor\" data-id=\"2826f3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span style=\"color: #000080;\"><strong>Depuis le lundi 28 septembre, Transvilles lance une campagne de communication d\u00e9cal\u00e9e pour inciter ses clients \u00e0 valider \u00e0 bord des trams et des bus. L\u2019objectif est d\u2019interpeler les clients sur l\u2019importance de cet acte obligatoire, qui est n\u00e9cessaire au bon fonctionnement du r\u00e9seau.<\/strong><\/span><\/h6><h6><span style=\"color: #993300;\"><strong>La validation : un acte n\u00e9cessaire<\/strong><\/span><\/h6><p>Valider son titre de transport est un acte obligatoire pour voyager en r\u00e8gle. La non validation est r\u00e9pr\u00e9hensible et entraine une amende allant de 5\u20ac (abonnement) \u00e0 33\u20ac (ticket). Il est rappel\u00e9 que l\u2019absence d\u2019un titre de transport peut entrainer, quant \u00e0 elle, une p\u00e9nalit\u00e9 financi\u00e8re de 50 \u20ac.<\/p><p>Au-del\u00e0 du caract\u00e8re r\u00e9glementaire de cet acte, les validations permettant de mesurer la fr\u00e9quentation sur les lignes, en fonction des arr\u00eats et des tranches horaires. Elles servent \u00e0 dessiner une cartographie pr\u00e9cise de l\u2019affluence sur le r\u00e9seau pour pouvoir adapter les moyens humains et techniques aux besoins des clients.<br \/>En cette p\u00e9riode de crise sanitaire, elles sont d\u2019autant plus utiles pour \u00e9valuer la fr\u00e9quentation aux heures de pointe et ajuster les voyages dans le respect des r\u00e8gles sanitaires.<\/p><p>Enfin, pour des raisons de s\u00e9curit\u00e9, un titre de transport valid\u00e9 sert de preuve en cas de litige ou incident mat\u00e9riel ou corporel.<\/p><h6><span style=\"color: #993300;\">Une campagne d\u00e9cal\u00e9e pour donner une autre image des transports<\/span><\/h6><p>Afin d\u2019interpeler les clients sur cette obligation, nous avons opt\u00e9 pour un ton humoristique, en r\u00e9f\u00e9rence au cin\u00e9ma. Pour cette campagne aussi l\u00e9g\u00e8re qu\u2019originale, nous voulions varier les supports de communication et les messages afin de parler \u00e0 tous nos clients ; tant par leurs r\u00e9f\u00e9rences cin\u00e9matographiques que par les lieux qu\u2019ils fr\u00e9quentent.<\/p><p>5 affiches de cin\u00e9ma ont ainsi \u00e9t\u00e9 adapt\u00e9es pour 5 messages. Elles sont visibles sur 5 rames de tram et 5 bus articul\u00e9s. Le p\u00f4le d\u2019\u00e9change d\u2019Anzin est \u00e9galement habill\u00e9 aux couleurs d\u2019un des films.<\/p><p>Les agences commerciales de Denain et Valenciennes relayent aussi cette op\u00e9ration de sensibilisation haute en couleurs.<\/p><h6><span style=\"color: #993300;\">Transvilles rappelle les consignes de pr\u00e9caution<\/span><\/h6><p>Pour voyager avec Transvilles en toute s\u00e9r\u00e9nit\u00e9, les clients doivent respecter les gestes barri\u00e8res suivants, autant que possible :<\/p><ul><li>Porter un masque en station et dans le v\u00e9hicule, d\u00e8s que vous avez plus de 11 ans,<\/li><li>Se nettoyer les mains en montant dans le v\u00e9hicule avec du gel hydro-alcoolique,<\/li><li>Garder vos distances avec les autres passagers d&#8217;au moins un m\u00e8tre,<\/li><li>S&#8217;asseoir en priorit\u00e9 sur les assises c\u00f4t\u00e9 fen\u00eatre pour maintenir les distances avec les autres,<\/li><li>Reporter ses d\u00e9placements quand c&#8217;est possible, en dehors des heures de pointe,<\/li><li>\u00c9ternuer dans son coude.<\/li><\/ul><p>En parall\u00e8le et \u00e0 partir du 12 octobre, 5 rames de tramway seront habill\u00e9es afin de rappeler l\u2019obligation du masque \u00e0 bord.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bbd7bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bbd7bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f4b479\" data-id=\"5f4b479\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>TRANSVILLES RAPPELLE A SES CLIENTS AVEC HUMOUR L\u2019IMPORTANCE DE VALIDER Depuis le lundi 28 septembre, Transvilles lance une campagne de communication d\u00e9cal\u00e9e pour inciter ses clients \u00e0 valider \u00e0 bord des trams et des bus. L\u2019objectif est d\u2019interpeler les clients sur l\u2019importance de cet acte obligatoire, qui est n\u00e9cessaire au bon fonctionnement du r\u00e9seau. La [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[282],"tags":[380,377,382,383,381,379,378],"class_list":["post-1630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transvilles","tag-bon-fonctionnement-du-reseau","tag-campagne","tag-decale","tag-films","tag-reseau","tag-titre-de-transport","tag-validation","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campagne de validation - Ville de Thiant<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campagne de validation - Ville de Thiant\" \/>\n<meta property=\"og:description\" content=\"TRANSVILLES RAPPELLE A SES CLIENTS AVEC HUMOUR L\u2019IMPORTANCE DE VALIDER Depuis le lundi 28 septembre, Transvilles lance une campagne de communication d\u00e9cal\u00e9e pour inciter ses clients \u00e0 valider \u00e0 bord des trams et des bus. L\u2019objectif est d\u2019interpeler les clients sur l\u2019importance de cet acte obligatoire, qui est n\u00e9cessaire au bon fonctionnement du r\u00e9seau. La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/\" \/>\n<meta property=\"og:site_name\" content=\"Ville de Thiant\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-05T12:22:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-14T13:52:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/03\/logo-transvilles-600.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"171\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Service communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Service communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/\"},\"author\":{\"name\":\"Service communication\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\"},\"headline\":\"Campagne de validation\",\"datePublished\":\"2020-10-05T12:22:03+00:00\",\"dateModified\":\"2020-10-14T13:52:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/\"},\"wordCount\":491,\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo-transvilles-600.png\",\"keywords\":[\"bon fonctionnement du r\u00e9seau\",\"campagne\",\"d\u00e9cal\u00e9\",\"films\",\"r\u00e9seau\",\"titre de transport\",\"validation\"],\"articleSection\":[\"TRANSVILLES\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/\",\"name\":\"Campagne de validation - Ville de Thiant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo-transvilles-600.png\",\"datePublished\":\"2020-10-05T12:22:03+00:00\",\"dateModified\":\"2020-10-14T13:52:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo-transvilles-600.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo-transvilles-600.png\",\"width\":600,\"height\":171},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/campagne-de-validation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagne de validation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/\",\"name\":\"Ville de Thiant\",\"description\":\"Site officiel de la ville de Thiant\",\"publisher\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#organization\",\"name\":\"Ville de Thiant\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Thiant_Illdy_4.png\",\"contentUrl\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Thiant_Illdy_4.png\",\"width\":105,\"height\":75,\"caption\":\"Ville de Thiant\"},\"image\":{\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/#\\\/schema\\\/person\\\/f41122130d18c0720657431d990451c6\",\"name\":\"Service communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/527d4f1f1330a82db5a7ea7738ddeb994fd26c4537512a833d99b387808ee250?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/527d4f1f1330a82db5a7ea7738ddeb994fd26c4537512a833d99b387808ee250?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/527d4f1f1330a82db5a7ea7738ddeb994fd26c4537512a833d99b387808ee250?s=96&r=g\",\"caption\":\"Service communication\"},\"url\":\"https:\\\/\\\/thiant.fr\\\/wordpress\\\/author\\\/adminwpress\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campagne de validation - Ville de Thiant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/","og_locale":"fr_FR","og_type":"article","og_title":"Campagne de validation - Ville de Thiant","og_description":"TRANSVILLES RAPPELLE A SES CLIENTS AVEC HUMOUR L\u2019IMPORTANCE DE VALIDER Depuis le lundi 28 septembre, Transvilles lance une campagne de communication d\u00e9cal\u00e9e pour inciter ses clients \u00e0 valider \u00e0 bord des trams et des bus. L\u2019objectif est d\u2019interpeler les clients sur l\u2019importance de cet acte obligatoire, qui est n\u00e9cessaire au bon fonctionnement du r\u00e9seau. La [&hellip;]","og_url":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/","og_site_name":"Ville de Thiant","article_published_time":"2020-10-05T12:22:03+00:00","article_modified_time":"2020-10-14T13:52:13+00:00","og_image":[{"width":600,"height":171,"url":"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/03\/logo-transvilles-600.png","type":"image\/png"}],"author":"Service communication","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Service communication","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/#article","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/"},"author":{"name":"Service communication","@id":"https:\/\/thiant.fr\/wordpress\/#\/schema\/person\/f41122130d18c0720657431d990451c6"},"headline":"Campagne de validation","datePublished":"2020-10-05T12:22:03+00:00","dateModified":"2020-10-14T13:52:13+00:00","mainEntityOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/"},"wordCount":491,"publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/#organization"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/03\/logo-transvilles-600.png","keywords":["bon fonctionnement du r\u00e9seau","campagne","d\u00e9cal\u00e9","films","r\u00e9seau","titre de transport","validation"],"articleSection":["TRANSVILLES"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/","url":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/","name":"Campagne de validation - Ville de Thiant","isPartOf":{"@id":"https:\/\/thiant.fr\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/#primaryimage"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/#primaryimage"},"thumbnailUrl":"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/03\/logo-transvilles-600.png","datePublished":"2020-10-05T12:22:03+00:00","dateModified":"2020-10-14T13:52:13+00:00","breadcrumb":{"@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/#primaryimage","url":"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/03\/logo-transvilles-600.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2020\/03\/logo-transvilles-600.png","width":600,"height":171},{"@type":"BreadcrumbList","@id":"https:\/\/thiant.fr\/wordpress\/campagne-de-validation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/thiant.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Campagne de validation"}]},{"@type":"WebSite","@id":"https:\/\/thiant.fr\/wordpress\/#website","url":"https:\/\/thiant.fr\/wordpress\/","name":"Ville de Thiant","description":"Site officiel de la ville de Thiant","publisher":{"@id":"https:\/\/thiant.fr\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thiant.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/thiant.fr\/wordpress\/#organization","name":"Ville de Thiant","url":"https:\/\/thiant.fr\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thiant.fr\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2019\/08\/Thiant_Illdy_4.png","contentUrl":"https:\/\/thiant.fr\/wordpress\/wp-content\/uploads\/2019\/08\/Thiant_Illdy_4.png","width":105,"height":75,"caption":"Ville de Thiant"},"image":{"@id":"https:\/\/thiant.fr\/wordpress\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/thiant.fr\/wordpress\/#\/schema\/person\/f41122130d18c0720657431d990451c6","name":"Service communication","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/527d4f1f1330a82db5a7ea7738ddeb994fd26c4537512a833d99b387808ee250?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/527d4f1f1330a82db5a7ea7738ddeb994fd26c4537512a833d99b387808ee250?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/527d4f1f1330a82db5a7ea7738ddeb994fd26c4537512a833d99b387808ee250?s=96&r=g","caption":"Service communication"},"url":"https:\/\/thiant.fr\/wordpress\/author\/adminwpress\/"}]}},"_links":{"self":[{"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=1630"}],"version-history":[{"count":0,"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/media\/1158"}],"wp:attachment":[{"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=1630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=1630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thiant.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=1630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}